{"id":8783,"date":"2025-02-17T17:13:25","date_gmt":"2025-02-17T17:13:25","guid":{"rendered":"https:\/\/acetaiasereni.com\/senza-categoria\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/"},"modified":"2026-02-23T16:43:39","modified_gmt":"2026-02-23T16:43:39","slug":"1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio","status":"publish","type":"post","link":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/","title":{"rendered":"Brioche, Fegatini e Aceto Balsamico di Modena"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8783\" class=\"elementor elementor-8783 elementor-5374\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b9624a e-flex e-con-boxed e-con e-parent\" data-id=\"5b9624a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af51077 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"af51077\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-e973e1a swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"image00007\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Brioche, Fegatini &amp; Aceto Balsamico di Modena<\/div><div class=\"elementor-slide-description\"><p>Pan brioche tostato con fegatini, cipolla caramellata e Aceto Balsamico di Modena IGP invecchiato \"Ciliegio\"<\/p>\n<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-838bcec elementor-widget elementor-widget-heading\" data-id=\"838bcec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acetaia Sereni Chef Ambassador: Alessio Da Prato, Chef toscano e co-proprietario di Toscana Saporita, ha preparato per noi una nuova ricetta con il Balsamico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dfd2768 e-flex e-con-boxed e-con e-parent\" data-id=\"dfd2768\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b9aeec elementor-widget elementor-widget-text-editor\" data-id=\"1b9aeec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>Ingredienti<\/strong><\/span><\/p><ul><li>Pane brioche salato, affettato e tostato<\/li><li>Pat\u00e9 di fegatini di pollo<\/li><li>Cipolla rossa, tagliata sottile<\/li><li>Aceto Balsamico di Modena IGP Sereni, invecchiato 8 anni in botti di ciliegio<\/li><li>Zucchero di canna<\/li><li>Burro non salato<\/li><li>Olio Extravergine d&#8217;Oliva<\/li><li>Sale e pepe nero<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af1b1e8 e-flex e-con-boxed e-con e-parent\" data-id=\"af1b1e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1a57b7e e-con-full e-flex e-con e-child\" data-id=\"1a57b7e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdfc06b elementor-widget elementor-widget-text-editor\" data-id=\"fdfc06b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Caramellizzare le cipolle<\/strong> come segue:<\/p><ul><li style=\"text-align: center;\">Cuocere lentamente le cipolle in un mix di burro ed Olio EVO finch\u00e9 non si ammorbidiscono.<\/li><li style=\"text-align: center;\">Aggiungere alle cipolle lo zucchero di canna e farlo sciogliere, quindi versare l&#8217;Aceto Balsamico IGP \u201cCiliegio\u201d Sereni e farlo ridurre.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09e7dfb elementor-widget elementor-widget-image\" data-id=\"09e7dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/image00020-scaled-e1760690735185.jpeg\" class=\"attachment-full size-full wp-image-9175\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38ae6de e-con-full e-flex e-con e-child\" data-id=\"38ae6de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65ea992 elementor-widget elementor-widget-image\" data-id=\"65ea992\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/briosche-4-1-scaled-e1760691055851.jpeg\" class=\"attachment-full size-full wp-image-9182\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e58d4fa elementor-widget elementor-widget-text-editor\" data-id=\"e58d4fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"> <strong>Tostare leggermente le fette di pan brioche<\/strong> fino a quando non diventeranno dorate e croccante<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e846fe8 e-con-full e-flex e-con e-child\" data-id=\"e846fe8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3c236 elementor-widget elementor-widget-text-editor\" data-id=\"5f3c236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Assemblaggio<\/strong>:<strong style=\"background-color: transparent; word-spacing: 0em;\"> spalma<\/strong> <span style=\"background-color: transparent; word-spacing: 0em;\">uno strato generoso <\/span>di<strong style=\"background-color: transparent; word-spacing: 0em;\"> p\u00e2t\u00e9 di fegatini di pollo<\/strong> <span style=\"background-color: transparent; word-spacing: 0em;\">sul pane brioche tostato. <\/span><span style=\"background-color: transparent; word-spacing: 0em;\">Completa con le <\/span> <strong style=\"background-color: transparent; word-spacing: 0em;\">cipolle caramellate<\/strong> all\u2019aceto balsamico. <span style=\"background-color: transparent; word-spacing: 0em;\">Aggiungi, a piacere<\/span>, <strong style=\"background-color: transparent; word-spacing: 0em;\">qualche goccia di Aceto Balsamico IGP Sereni \u201cCiliegio\u201d <\/strong><span style=\"background-color: transparent; word-spacing: 0em;\">sul piatto finito.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99d4bab elementor-widget elementor-widget-image\" data-id=\"99d4bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/image00011-scaled-e1760691190732.jpeg\" class=\"attachment-full size-full wp-image-9188\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-718d96e e-flex e-con-boxed e-con e-parent\" data-id=\"718d96e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-817910e elementor-widget elementor-widget-heading\" data-id=\"817910e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servire e gustare!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a77551a e-flex e-con-boxed e-con e-parent\" data-id=\"a77551a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Lo Chef Ambassador Alessio Da Prato, chef toscano, ha realizzato una nuova ricetta con Aceto Balsamico firmato Acetaia Sereni: pan brioche tostato con fegatini di pollo, cipolle caramellate e Aceto Balsamico di Modena IGP invecchiato \u201cCiliegio\u201d di Acetaia Sereni<\/p>\n","protected":false},"author":2,"featured_media":8800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2672],"tags":[1844,1843,1951,1954,1958,1787,1956,2060,2061,2062,1959,2063,2064,1851,2059,2065,2055,1898,2066,2067,1977,1788,2068,2056,1949,2069,1955,2070,2071,2057,2072,1984,2058],"class_list":["post-8783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-receipes","tag-acetaia-sereni-it-2","tag-aceto-balsamico-it-2","tag-aceto-balsamico-di-modena-igp-it","tag-aged-it","tag-alessio-da-prato-it","tag-balsamic-vinegar-it","tag-balsamic-vinegar-of-modena-pgi-it","tag-bread-it","tag-brioche-bread-it","tag-brown-sugar-it","tag-butter-it","tag-caramelize-it","tag-caramelized-it","tag-chef-it","tag-chef-ambassador-it","tag-cherry-it","tag-cherry-barrels-it","tag-extra-virgin-olive-oil-it","tag-liver-chicken-it","tag-livers-it","tag-marano-sul-panaro-it","tag-modena-it","tag-onion-it","tag-pepper-it","tag-recipe-it","tag-reduction-it","tag-salt-it","tag-serve-it","tag-sugar-it","tag-taste-it","tag-toast-it","tag-toscana-saporita-it","tag-wood-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chef Ambassador Alessio Da Prato: ricetta con Balsamico Sereni<\/title>\n<meta name=\"description\" content=\"Chef Ambassador Alessio Da Prato ha preparato una nuova ricetta: pan brioche tostato con fegatini di pollo e cipolle caramellate all&#039;Aceto Balsamico di Modena IGP &quot;Ciliegio&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chef Ambassador Alessio Da Prato: ricetta con Balsamico Sereni\" \/>\n<meta property=\"og:description\" content=\"Chef Ambassador Alessio Da Prato ha preparato una nuova ricetta: pan brioche tostato con fegatini di pollo e cipolle caramellate all&#039;Aceto Balsamico di Modena IGP &quot;Ciliegio&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/\" \/>\n<meta property=\"og:site_name\" content=\"Acetaia Sereni\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T17:13:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T16:43:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/image00007-scaled-e1769521746707.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"acetaiasereni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"acetaiasereni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/\"},\"author\":{\"name\":\"acetaiasereni\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#\\\/schema\\\/person\\\/bbc23e208df251ec8b3a6d6bd376cdc1\"},\"headline\":\"Brioche, Fegatini e Aceto Balsamico di Modena\",\"datePublished\":\"2025-02-17T17:13:25+00:00\",\"dateModified\":\"2026-02-23T16:43:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/\"},\"wordCount\":222,\"publisher\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image00007-scaled-e1769521746707.jpeg\",\"keywords\":[\"acetaia sereni\",\"Aceto Balsamico\",\"Aceto Balsamico di Modena IGP\",\"aged\",\"Alessio da Prato\",\"Balsamic Vinegar\",\"Balsamic Vinegar of Modena PGI\",\"bread\",\"brioche bread\",\"brown sugar\",\"butter\",\"caramelize\",\"caramelized\",\"chef\",\"Chef Ambassador\",\"cherry\",\"Cherry barrels\",\"Extra Virgin Olive Oil\",\"liver chicken\",\"livers\",\"Marano sul Panaro\",\"Modena\",\"onion\",\"pepper\",\"recipe\",\"reduction\",\"salt\",\"serve\",\"sugar\",\"taste\",\"toast\",\"Toscana Saporita\",\"wood\"],\"articleSection\":[\"Receipes\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/\",\"name\":\"Chef Ambassador Alessio Da Prato: ricetta con Balsamico Sereni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image00007-scaled-e1769521746707.jpeg\",\"datePublished\":\"2025-02-17T17:13:25+00:00\",\"dateModified\":\"2026-02-23T16:43:39+00:00\",\"description\":\"Chef Ambassador Alessio Da Prato ha preparato una nuova ricetta: pan brioche tostato con fegatini di pollo e cipolle caramellate all'Aceto Balsamico di Modena IGP \\\"Ciliegio\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image00007-scaled-e1769521746707.jpeg\",\"contentUrl\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image00007-scaled-e1769521746707.jpeg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brioche, Fegatini e Aceto Balsamico di Modena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/\",\"name\":\"Acetaia Sereni\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#organization\",\"name\":\"Acetaia Sereni\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-acetaia-sereni.png\",\"contentUrl\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-acetaia-sereni.png\",\"width\":1200,\"height\":1086,\"caption\":\"Acetaia Sereni\"},\"image\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#\\\/schema\\\/person\\\/bbc23e208df251ec8b3a6d6bd376cdc1\",\"name\":\"acetaiasereni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g\",\"caption\":\"acetaiasereni\"},\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/author\\\/acetaiasereni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chef Ambassador Alessio Da Prato: ricetta con Balsamico Sereni","description":"Chef Ambassador Alessio Da Prato ha preparato una nuova ricetta: pan brioche tostato con fegatini di pollo e cipolle caramellate all'Aceto Balsamico di Modena IGP \"Ciliegio\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/","og_locale":"it_IT","og_type":"article","og_title":"Chef Ambassador Alessio Da Prato: ricetta con Balsamico Sereni","og_description":"Chef Ambassador Alessio Da Prato ha preparato una nuova ricetta: pan brioche tostato con fegatini di pollo e cipolle caramellate all'Aceto Balsamico di Modena IGP \"Ciliegio\"","og_url":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/","og_site_name":"Acetaia Sereni","article_published_time":"2025-02-17T17:13:25+00:00","article_modified_time":"2026-02-23T16:43:39+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/image00007-scaled-e1769521746707.jpeg","type":"image\/jpeg"}],"author":"acetaiasereni","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"acetaiasereni","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/#article","isPartOf":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/"},"author":{"name":"acetaiasereni","@id":"https:\/\/acetaiasereni.com\/it\/#\/schema\/person\/bbc23e208df251ec8b3a6d6bd376cdc1"},"headline":"Brioche, Fegatini e Aceto Balsamico di Modena","datePublished":"2025-02-17T17:13:25+00:00","dateModified":"2026-02-23T16:43:39+00:00","mainEntityOfPage":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/"},"wordCount":222,"publisher":{"@id":"https:\/\/acetaiasereni.com\/it\/#organization"},"image":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/#primaryimage"},"thumbnailUrl":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/image00007-scaled-e1769521746707.jpeg","keywords":["acetaia sereni","Aceto Balsamico","Aceto Balsamico di Modena IGP","aged","Alessio da Prato","Balsamic Vinegar","Balsamic Vinegar of Modena PGI","bread","brioche bread","brown sugar","butter","caramelize","caramelized","chef","Chef Ambassador","cherry","Cherry barrels","Extra Virgin Olive Oil","liver chicken","livers","Marano sul Panaro","Modena","onion","pepper","recipe","reduction","salt","serve","sugar","taste","toast","Toscana Saporita","wood"],"articleSection":["Receipes"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/","url":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/","name":"Chef Ambassador Alessio Da Prato: ricetta con Balsamico Sereni","isPartOf":{"@id":"https:\/\/acetaiasereni.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/#primaryimage"},"image":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/#primaryimage"},"thumbnailUrl":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/image00007-scaled-e1769521746707.jpeg","datePublished":"2025-02-17T17:13:25+00:00","dateModified":"2026-02-23T16:43:39+00:00","description":"Chef Ambassador Alessio Da Prato ha preparato una nuova ricetta: pan brioche tostato con fegatini di pollo e cipolle caramellate all'Aceto Balsamico di Modena IGP \"Ciliegio\"","breadcrumb":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/#primaryimage","url":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/image00007-scaled-e1769521746707.jpeg","contentUrl":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/image00007-scaled-e1769521746707.jpeg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/acetaiasereni.com\/it\/receipes\/1-ricetta-pan-brioche-tostato-con-fegatini-cipolla-caramellata-e-aceto-balsamico-di-modena-igp-ciliegio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acetaiasereni.com\/it\/homepage\/"},{"@type":"ListItem","position":2,"name":"Brioche, Fegatini e Aceto Balsamico di Modena"}]},{"@type":"WebSite","@id":"https:\/\/acetaiasereni.com\/it\/#website","url":"https:\/\/acetaiasereni.com\/it\/","name":"Acetaia Sereni","description":"","publisher":{"@id":"https:\/\/acetaiasereni.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acetaiasereni.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/acetaiasereni.com\/it\/#organization","name":"Acetaia Sereni","url":"https:\/\/acetaiasereni.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acetaiasereni.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/logo-acetaia-sereni.png","contentUrl":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/logo-acetaia-sereni.png","width":1200,"height":1086,"caption":"Acetaia Sereni"},"image":{"@id":"https:\/\/acetaiasereni.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/acetaiasereni.com\/it\/#\/schema\/person\/bbc23e208df251ec8b3a6d6bd376cdc1","name":"acetaiasereni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g","caption":"acetaiasereni"},"url":"https:\/\/acetaiasereni.com\/it\/author\/acetaiasereni\/"}]}},"_links":{"self":[{"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/posts\/8783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/comments?post=8783"}],"version-history":[{"count":7,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/posts\/8783\/revisions"}],"predecessor-version":[{"id":12273,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/posts\/8783\/revisions\/12273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/media\/8800"}],"wp:attachment":[{"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/media?parent=8783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/categories?post=8783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/tags?post=8783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}