{"id":9220,"date":"2023-01-31T09:11:01","date_gmt":"2023-01-31T09:11:01","guid":{"rendered":"https:\/\/acetaiasereni.com\/senza-categoria\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/"},"modified":"2026-03-03T16:32:28","modified_gmt":"2026-03-03T16:32:28","slug":"ricetta-lenticchie-allaceto-balsamico-di-modena-igp","status":"publish","type":"post","link":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/","title":{"rendered":"Ricetta: Lenticchie all\u2019Aceto Balsamico di Modena IGP"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9220\" class=\"elementor elementor-9220 elementor-3685\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d768027 e-flex e-con-boxed e-con e-parent\" data-id=\"d768027\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3de3414 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"3de3414\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-f855b6d swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"DSC_0458-2\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Ricetta<\/div><div class=\"elementor-slide-description\"><p>Lenticchie con Aceto Balsamico di Modena IGP<\/p>\n<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6c2678 e-flex e-con-boxed e-con e-parent\" data-id=\"f6c2678\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f654ae elementor-widget elementor-widget-heading\" data-id=\"9f654ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Buon Inizio 2023! Con il desiderio di iniziare l\u2019anno nuovo sazi ma leggeri, ci rendiamo conto che qualcosa dello scorso Natale \u00e8 rimasto\u2026 una busta di lenticchie secche dal cesto di vostro zio! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f07364 e-flex e-con-boxed e-con e-parent\" data-id=\"0f07364\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efaa8d0 elementor-widget elementor-widget-text-editor\" data-id=\"efaa8d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ecco come trasformare un avanzo delle feste in un piatto piacevole e originale, ricco di proteine e carboidrati complessi, perfetto per rimettersi in forma dopo le feste! <\/p><p>Potrete anche proporre questa variante di lenticchie il prossimo Natale, con grande sorpresa: lenticchie con aceto balsamico!<\/p><p><strong>Vediamo insieme come procedere:<\/strong><\/p><p><em>Difficolt\u00e0<\/em>: Medio\/Facile<\/p><p><em>Porzioni<\/em>: 6 persone<\/p><p>Tempo di preparazione: 45 minutes<\/p><p>Tempo di cottura: 30\/35 minutes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-228229f e-flex e-con-boxed e-con e-parent\" data-id=\"228229f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-62c1ad1 e-con-full e-flex e-con e-child\" data-id=\"62c1ad1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0dbb52 elementor-widget elementor-widget-text-editor\" data-id=\"c0dbb52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\">Ingredienti:<\/span><\/p><ul><li>Lenticchie secche (rosse o verdi) 500 g<\/li><li>1 cipolla dorata media o 3 scalogni<\/li><li>Olio Extra Vergine di Oliva Acetaia Sereni \u201cIl D\u00f2lz\u201d q.b.<\/li><li>Rosmarino fresco o secco q.b.<\/li><li>3\/4 foglie di alloro, anche secco<\/li><li>4\/5 foglie di salvia, anche secca<\/li><li>Pepe bianco q.b. (facoltativo)<\/li><li>Sale fino q.b.<\/li><li>Aceto Balsamico di Modena IGP Acetaia Sereni, invecchiato 8 anni in botti di ciliegio<\/li><li>Acqua q.b.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfa5dab e-con-full e-flex e-con e-child\" data-id=\"cfa5dab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ce9eb4 elementor-widget elementor-widget-image\" data-id=\"5ce9eb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude.png\" class=\"attachment-full size-full wp-image-8254\" alt=\"\" srcset=\"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude.png 800w, https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude-300x300.png 300w, https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude-150x150.png 150w, https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude-768x768.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a683ac1 e-flex e-con-boxed e-con e-parent\" data-id=\"a683ac1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5003c80 elementor-widget elementor-widget-text-editor\" data-id=\"5003c80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\">Preparazione:<\/span><\/p><ol><li><strong style=\"background-color: transparent; word-spacing: 0em;\">Lavare<\/strong><span style=\"background-color: transparent; word-spacing: 0em;\"> le lenticchie sotto acqua corrente. Non \u00e8 necessario reidratarli lasciandoli in acqua la sera prima, sono gi\u00e0 pronti per essere utilizzati.<\/span><\/li><li>Tagliare la <strong>cipolla (o gli scalogni)<\/strong> a fette grosse, non \u00e8 necessario ridurle a cubetti piccoli.<\/li><li>Versare e scaldare l\u2019olio Il D\u00f2lz in una padella dai bordi alti (casseruola), coprendo tutto il fondo.<\/li><li>Mettere le cipolle nell\u2019olio e farle appassire per 5-6 minuti.<\/li><li>Quando la cipolla \u00e8 trasparente, aggiungere le <strong>lenticchie <\/strong>nella casseruola insieme a<strong> rosmarino, alloro e salvia<\/strong>. Se volete, potete legare le erbe a formare un mazzetto aromatico da rimuovere a fine cottura. <\/li><li>Versare 4-5 cucchiai di Aceto Balsamico di Modena IGP invecchiato in botti di ciliegio sulle lenticchie.<\/li><li>Riempire la casseruola con <strong>acqua calda<\/strong> fino a coprire completamente le lenticchie.<\/li><li>Mescolare e far <strong>cuocere a fuoco basso<\/strong>, senza coperchio e senza sale, per circa 30 minuti.<\/li><li>Durante la cottura, <strong>mescolare <\/strong>di tanto in tanto e, se l\u2019acqua si asciuga prima che le lenticchie siano pronte, aggiungere altra acqua calda.<\/li><li><strong>Assaggiare le lenticchie<\/strong> per verificarne la consistenza e la cottura.<\/li><li>Verso fine cottura, <strong>aggiungere sale e pepe<\/strong> a piacere.<\/li><li><strong>Servire <\/strong>le lenticchie ancora calde.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39a55a6 e-flex e-con-boxed e-con e-parent\" data-id=\"39a55a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f88afaa elementor-widget elementor-widget-text-editor\" data-id=\"f88afaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se non le consumate subito: lasciarle raffreddare bene, preparare porzioni da 90 g in sacchetti per il freezer e <strong>congelarle<\/strong>. Saranno pronte in qualsiasi momento come piatto unico, contorno o condimento per pasta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b83628f e-flex e-con-boxed e-con e-parent\" data-id=\"b83628f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b74f39 elementor-widget elementor-widget-heading\" data-id=\"2b74f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tocco finale: una goccia di olio EVO Sereni \u201cIl Calancolle\u201d! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06bc13d e-flex e-con-boxed e-con e-parent\" data-id=\"06bc13d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbf77df elementor-widget elementor-widget-text-editor\" data-id=\"dbf77df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vuoi acquistare il nostro Aceto Balsamico di Modena IGP invecchiato in botti di ciliegio? <span style=\"text-decoration: underline;\"><a href=\"https:\/\/shop.acetaiasereni.com\/collections\/igp\/products\/aceto-balsamico-di-modena-i-g-p-invecchiato-etichetta-arancione\">Clicca qui<\/a><\/span>!<\/p><p>Vuoi acquistare i nostro Oli Extra Vergini d&#8217;Oliva? <span style=\"text-decoration: underline;\"><a href=\"https:\/\/shop.acetaiasereni.com\/collections\/olio-e-lambrusco\">Clicca qui<\/a><\/span>!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Acetaia Sereni vi propone una ricetta post-natalizia con lenticchie, Aceto Balsamico di Modena IGP invecchiato in botti di ciliegio e i suoi Oli Extra Vergine di Oliva dell\u2019Alta Modena: Il D\u00f2lz e Il Calancolle!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2672],"tags":[1844,1787,2463,2055,2637,2464,1898,2638,1788,1842,1949,1846],"class_list":["post-9220","post","type-post","status-publish","format-standard","hentry","category-receipes","tag-acetaia-sereni-it-2","tag-balsamic-vinegar-it","tag-calancolle-it","tag-cherry-barrels-it","tag-christmas","tag-dolz-it","tag-extra-virgin-olive-oil-it","tag-lentis","tag-modena-it","tag-olio-it","tag-recipe-it","tag-sereni-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ricetta di Acetaia Sereni: lenticchie e Aceto Balsamico di Modena IGP<\/title>\n<meta name=\"description\" content=\"Acetaia Sereni vi propone una ricetta post-natalizia con lenticchie, Aceto Balsamico di Modena invecchiato in botti di ciliegio e i suoi Oli Extra Vergine di Oliva dell\u2019Alta Modena.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricetta di Acetaia Sereni: lenticchie e Aceto Balsamico di Modena IGP\" \/>\n<meta property=\"og:description\" content=\"Acetaia Sereni vi propone una ricetta post-natalizia con lenticchie, Aceto Balsamico di Modena invecchiato in botti di ciliegio e i suoi Oli Extra Vergine di Oliva dell\u2019Alta Modena.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/\" \/>\n<meta property=\"og:site_name\" content=\"Acetaia Sereni\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-31T09:11:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T16:32:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"acetaiasereni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"acetaiasereni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/\"},\"author\":{\"name\":\"acetaiasereni\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#\\\/schema\\\/person\\\/bbc23e208df251ec8b3a6d6bd376cdc1\"},\"headline\":\"Ricetta: Lenticchie all\u2019Aceto Balsamico di Modena IGP\",\"datePublished\":\"2023-01-31T09:11:01+00:00\",\"dateModified\":\"2026-03-03T16:32:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/\"},\"wordCount\":431,\"publisher\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Scodella-di-lenticchie-crude.png\",\"keywords\":[\"acetaia sereni\",\"Balsamic Vinegar\",\"Calancolle\",\"Cherry barrels\",\"Christmas\",\"Dolz\",\"Extra Virgin Olive Oil\",\"Lentis\",\"Modena\",\"Olio\",\"recipe\",\"sereni\"],\"articleSection\":[\"Receipes\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/\",\"name\":\"Ricetta di Acetaia Sereni: lenticchie e Aceto Balsamico di Modena IGP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Scodella-di-lenticchie-crude.png\",\"datePublished\":\"2023-01-31T09:11:01+00:00\",\"dateModified\":\"2026-03-03T16:32:28+00:00\",\"description\":\"Acetaia Sereni vi propone una ricetta post-natalizia con lenticchie, Aceto Balsamico di Modena invecchiato in botti di ciliegio e i suoi Oli Extra Vergine di Oliva dell\u2019Alta Modena.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Scodella-di-lenticchie-crude.png\",\"contentUrl\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Scodella-di-lenticchie-crude.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/receipes\\\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricetta: Lenticchie all\u2019Aceto Balsamico di Modena IGP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/\",\"name\":\"Acetaia Sereni\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#organization\",\"name\":\"Acetaia Sereni\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-acetaia-sereni.png\",\"contentUrl\":\"https:\\\/\\\/acetaiasereni.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-acetaia-sereni.png\",\"width\":1200,\"height\":1086,\"caption\":\"Acetaia Sereni\"},\"image\":{\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/#\\\/schema\\\/person\\\/bbc23e208df251ec8b3a6d6bd376cdc1\",\"name\":\"acetaiasereni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g\",\"caption\":\"acetaiasereni\"},\"url\":\"https:\\\/\\\/acetaiasereni.com\\\/it\\\/author\\\/acetaiasereni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricetta di Acetaia Sereni: lenticchie e Aceto Balsamico di Modena IGP","description":"Acetaia Sereni vi propone una ricetta post-natalizia con lenticchie, Aceto Balsamico di Modena invecchiato in botti di ciliegio e i suoi Oli Extra Vergine di Oliva dell\u2019Alta Modena.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/","og_locale":"it_IT","og_type":"article","og_title":"Ricetta di Acetaia Sereni: lenticchie e Aceto Balsamico di Modena IGP","og_description":"Acetaia Sereni vi propone una ricetta post-natalizia con lenticchie, Aceto Balsamico di Modena invecchiato in botti di ciliegio e i suoi Oli Extra Vergine di Oliva dell\u2019Alta Modena.","og_url":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/","og_site_name":"Acetaia Sereni","article_published_time":"2023-01-31T09:11:01+00:00","article_modified_time":"2026-03-03T16:32:28+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude.png","type":"image\/png"}],"author":"acetaiasereni","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"acetaiasereni","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/#article","isPartOf":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/"},"author":{"name":"acetaiasereni","@id":"https:\/\/acetaiasereni.com\/it\/#\/schema\/person\/bbc23e208df251ec8b3a6d6bd376cdc1"},"headline":"Ricetta: Lenticchie all\u2019Aceto Balsamico di Modena IGP","datePublished":"2023-01-31T09:11:01+00:00","dateModified":"2026-03-03T16:32:28+00:00","mainEntityOfPage":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/"},"wordCount":431,"publisher":{"@id":"https:\/\/acetaiasereni.com\/it\/#organization"},"image":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/#primaryimage"},"thumbnailUrl":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude.png","keywords":["acetaia sereni","Balsamic Vinegar","Calancolle","Cherry barrels","Christmas","Dolz","Extra Virgin Olive Oil","Lentis","Modena","Olio","recipe","sereni"],"articleSection":["Receipes"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/","url":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/","name":"Ricetta di Acetaia Sereni: lenticchie e Aceto Balsamico di Modena IGP","isPartOf":{"@id":"https:\/\/acetaiasereni.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/#primaryimage"},"image":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/#primaryimage"},"thumbnailUrl":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude.png","datePublished":"2023-01-31T09:11:01+00:00","dateModified":"2026-03-03T16:32:28+00:00","description":"Acetaia Sereni vi propone una ricetta post-natalizia con lenticchie, Aceto Balsamico di Modena invecchiato in botti di ciliegio e i suoi Oli Extra Vergine di Oliva dell\u2019Alta Modena.","breadcrumb":{"@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/#primaryimage","url":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude.png","contentUrl":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2023\/01\/Scodella-di-lenticchie-crude.png"},{"@type":"BreadcrumbList","@id":"https:\/\/acetaiasereni.com\/it\/receipes\/ricetta-lenticchie-allaceto-balsamico-di-modena-igp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acetaiasereni.com\/it\/homepage\/"},{"@type":"ListItem","position":2,"name":"Ricetta: Lenticchie all\u2019Aceto Balsamico di Modena IGP"}]},{"@type":"WebSite","@id":"https:\/\/acetaiasereni.com\/it\/#website","url":"https:\/\/acetaiasereni.com\/it\/","name":"Acetaia Sereni","description":"","publisher":{"@id":"https:\/\/acetaiasereni.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acetaiasereni.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/acetaiasereni.com\/it\/#organization","name":"Acetaia Sereni","url":"https:\/\/acetaiasereni.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acetaiasereni.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/logo-acetaia-sereni.png","contentUrl":"https:\/\/acetaiasereni.com\/wp-content\/uploads\/2025\/02\/logo-acetaia-sereni.png","width":1200,"height":1086,"caption":"Acetaia Sereni"},"image":{"@id":"https:\/\/acetaiasereni.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/acetaiasereni.com\/it\/#\/schema\/person\/bbc23e208df251ec8b3a6d6bd376cdc1","name":"acetaiasereni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78abc3076748e76b87d9716c0946c9142c7837b44a11acac1d464456c27ffa44?s=96&d=mm&r=g","caption":"acetaiasereni"},"url":"https:\/\/acetaiasereni.com\/it\/author\/acetaiasereni\/"}]}},"_links":{"self":[{"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/posts\/9220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/comments?post=9220"}],"version-history":[{"count":2,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/posts\/9220\/revisions"}],"predecessor-version":[{"id":12336,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/posts\/9220\/revisions\/12336"}],"wp:attachment":[{"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/media?parent=9220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/categories?post=9220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acetaiasereni.com\/it\/wp-json\/wp\/v2\/tags?post=9220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}